{"id":27041,"date":"2023-10-24T09:00:00","date_gmt":"2023-10-24T12:00:00","guid":{"rendered":"https:\/\/weiku.com.br\/die-kraft-der-steine-angewendet-auf-die-corstone-belaege\/"},"modified":"2025-07-22T11:50:36","modified_gmt":"2025-07-22T14:50:36","slug":"die-kraft-der-steine-angewendet-auf-die-corstone-belaege","status":"publish","type":"post","link":"https:\/\/weiku.com.br\/de\/die-kraft-der-steine-angewendet-auf-die-corstone-belaege\/","title":{"rendered":"Die Kraft der Steine, angewendet auf die Corstone-Bel\u00e4ge."},"content":{"rendered":"\n<p>Wenn wir an die Bel\u00e4ge denken, die in den unterschiedlichsten Bauvorhaben eingesetzt werden, stehen Produkte wie Marmor und St\u00fccke aus Edelsteinen mit Sicherheit auf dieser Liste. Im Wohnzimmer, in der K\u00fcche, im Badezimmer, in M\u00f6beln \u2013 egal wo, immer wird es ein Zeichen dieser Materialien in Ihren Projekten geben.  <\/p>\n\n<p>Und um den Markt zu revolutionieren, bringt <a href=\"https:\/\/weiku.cordilheiramidias.com\/arquivos\/corstone_catalogo_2023_40p%C3%A1g_site.pdf\">Corstone<\/a> Pers\u00f6nlichkeit und Kreativit\u00e4t. Als erstes Belagsprodukt der Weiku-Gruppe sind Technologie und Vielseitigkeit die Worte, die die Marke am besten beschreiben. <\/p>\n\n<p>Hergestellt aus einer Vielzahl von Polymerfilmen, wird das Produkt durch einen Brennprozess zu einem Sicherheitsglas mit UV-Schutz.<\/p>\n\n<p>Unser Portfolio umfasst 30 Steine, davon 15 in der Kollektion der Edelsteine und 15 in der Kollektion der Marmorsteine. Sie erm\u00f6glichen eine Vielzahl von Kombinationen und Anwendungen, wie zum Beispiel f\u00fcr Decken, W\u00e4nde, M\u00f6bel, Schwimmb\u00e4der, Fassaden, Waschbecken und sogar Zubeh\u00f6r und Objekte. <\/p>\n\n<p>M\u00f6chten Sie mehr? Neben der M\u00f6glichkeit, in verschiedenen Umgebungen angewendet zu werden, kann das Material auch mit Hintergrundbeleuchtung versehen werden, was die einzigartigen Eigenschaften des Produkts exponentiell verst\u00e4rkt. <\/p>\n\n<p>Dar\u00fcber hinaus sind 15 unserer Referenzen auch in der Openbook-Option (bookmatched) erh\u00e4ltlich, die einen spiegelverkehrten Effekt der St\u00fccke erzeugt und eine der klassischsten und edelsten Pr\u00e4sentationsformen reproduziert.<\/p>\n\n<p>Nach dem Corstone Opaco und dem Corstone Transl\u00facido gibt es auch noch das Corstone Double Face. Ein noch exklusiveres und revolution\u00e4res Produkt, das Anwendungen wie Trennw\u00e4nde, T\u00fcren, Vitrinen, Duschabtrennungen und viele weitere erm\u00f6glicht \u2013 nur begrenzt durch Ihre Kreativit\u00e4t. Das Corstone Double Face hat das Design auf beiden Seiten (Vorder- und R\u00fcckseite), das hei\u00dft, beide Seiten zeigen das Aussehen des Steins. Es besitzt au\u00dferdem die Eigenschaft der Transluzenz.   <\/p>\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/weiku.cordilheiramidias.com\/wp-content\/uploads\/2023\/10\/IMG_2551-1024x768.jpeg\" alt=\"\" class=\"wp-image-16812\"\/><\/figure>\n<\/div>\n<\/div>\n\n<p>Die M\u00f6glichkeiten im Zusammenhang mit dem Produkt h\u00f6ren hier nicht auf. Corstone bietet auch die Satin-Version, eine Oberfl\u00e4chenbehandlung mit weniger Glanz und einer samtigen Haptik. Sie erf\u00fcllt die Nachfrage von Fachleuten, die in ihren Projekten weniger Reflexionen w\u00fcnschen.  <\/p>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/weiku.cordilheiramidias.com\/wp-content\/uploads\/2023\/10\/755-1024x819.jpg\" alt=\"\" class=\"wp-image-16813\"\/><\/figure>\n\n<p>F\u00fcr diejenigen, die satinierte und minimalistische Produkte bevorzugen, bietet die Textur mit \u201eSeidengriff\u201c in der Satin-Version der Corstone-Bel\u00e4ge einen einzigartigen Effekt im Raum, in dem sie angewendet wird, ohne dabei die Essenz der nat\u00fcrlichen Steinreferenzen zu verlieren.<\/p>\n\n<p>Die Standarddicke des Corstone-Belags betr\u00e4gt 9 mm und f\u00fcr spezielle Projekte kann er auf Anfrage in Dicken von 7 bis 20 mm hergestellt werden.<\/p>\n\n<p>Transluzent oder opak, in der gl\u00e4nzenden oder Satin-Version \u2013 revolutionieren Sie Ihre Art der Belaggestaltung mit Corstone.<\/p>\n\n<p class=\"has-text-align-center\"><a href=\"https:\/\/corstone.info\/pt-br\/onde-encontrar\"><strong>Corstone-H\u00e4ndler<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wenn wir an die Bel\u00e4ge denken, die in den unterschiedlichsten Bauvorhaben eingesetzt werden, stehen Produkte wie Marmor und St\u00fccke aus Edelsteinen mit Sicherheit auf dieser Liste. Im Wohnzimmer, in der K\u00fcche, im Badezimmer, in M\u00f6beln \u2013 egal wo, immer wird es ein Zeichen dieser Materialien in Ihren Projekten geben. Und um den Markt zu revolutionieren, [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":25284,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[726],"tags":[],"class_list":["post-27041","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nicht-kategorisiert"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Die Kraft der Steine, angewendet auf die Corstone-Bel\u00e4ge. - Weiku<\/title>\n<meta name=\"description\" content=\"Und um den Markt zu revolutionieren, kommt Corstone mit Pers\u00f6nlichkeit und Kreativit\u00e4t. Es ist das erste Belagsprodukt der Weiku-Gruppe...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/weiku.com.br\/de\/die-kraft-der-steine-angewendet-auf-die-corstone-belaege\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die Kraft der Steine, angewendet auf die Corstone-Bel\u00e4ge. - Weiku\" \/>\n<meta property=\"og:description\" content=\"Und um den Markt zu revolutionieren, kommt Corstone mit Pers\u00f6nlichkeit und Kreativit\u00e4t. Es ist das erste Belagsprodukt der Weiku-Gruppe...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/weiku.com.br\/de\/die-kraft-der-steine-angewendet-auf-die-corstone-belaege\/\" \/>\n<meta property=\"og:site_name\" content=\"Weiku\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-24T12:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-22T14:50:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/weiku.com.br\/wp-content\/uploads\/2023\/10\/banners-site-1024x431.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"431\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Mateus Fernandes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mateus Fernandes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/weiku.com.br\\\/de\\\/die-kraft-der-steine-angewendet-auf-die-corstone-belaege\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/weiku.com.br\\\/de\\\/die-kraft-der-steine-angewendet-auf-die-corstone-belaege\\\/\"},\"author\":{\"name\":\"Mateus Fernandes\",\"@id\":\"https:\\\/\\\/weiku.com.br\\\/de\\\/#\\\/schema\\\/person\\\/a15df1b49db4f0c34776a50f6a0ba70d\"},\"headline\":\"Die Kraft der Steine, angewendet auf die Corstone-Bel\u00e4ge.\",\"datePublished\":\"2023-10-24T12:00:00+00:00\",\"dateModified\":\"2025-07-22T14:50:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/weiku.com.br\\\/de\\\/die-kraft-der-steine-angewendet-auf-die-corstone-belaege\\\/\"},\"wordCount\":415,\"image\":{\"@id\":\"https:\\\/\\\/weiku.com.br\\\/de\\\/die-kraft-der-steine-angewendet-auf-die-corstone-belaege\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/weiku.com.br\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/banners-site.png\",\"articleSection\":[\"Nicht kategorisiert\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/weiku.com.br\\\/de\\\/die-kraft-der-steine-angewendet-auf-die-corstone-belaege\\\/\",\"url\":\"https:\\\/\\\/weiku.com.br\\\/de\\\/die-kraft-der-steine-angewendet-auf-die-corstone-belaege\\\/\",\"name\":\"Die Kraft der Steine, angewendet auf die Corstone-Bel\u00e4ge. - Weiku\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/weiku.com.br\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/weiku.com.br\\\/de\\\/die-kraft-der-steine-angewendet-auf-die-corstone-belaege\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/weiku.com.br\\\/de\\\/die-kraft-der-steine-angewendet-auf-die-corstone-belaege\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/weiku.com.br\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/banners-site.png\",\"datePublished\":\"2023-10-24T12:00:00+00:00\",\"dateModified\":\"2025-07-22T14:50:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/weiku.com.br\\\/de\\\/#\\\/schema\\\/person\\\/a15df1b49db4f0c34776a50f6a0ba70d\"},\"description\":\"Und um den Markt zu revolutionieren, kommt Corstone mit Pers\u00f6nlichkeit und Kreativit\u00e4t. Es ist das erste Belagsprodukt der Weiku-Gruppe...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/weiku.com.br\\\/de\\\/die-kraft-der-steine-angewendet-auf-die-corstone-belaege\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/weiku.com.br\\\/de\\\/die-kraft-der-steine-angewendet-auf-die-corstone-belaege\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/weiku.com.br\\\/de\\\/die-kraft-der-steine-angewendet-auf-die-corstone-belaege\\\/#primaryimage\",\"url\":\"https:\\\/\\\/weiku.com.br\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/banners-site.png\",\"contentUrl\":\"https:\\\/\\\/weiku.com.br\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/banners-site.png\",\"width\":1600,\"height\":673},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/weiku.com.br\\\/de\\\/die-kraft-der-steine-angewendet-auf-die-corstone-belaege\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/weiku.com.br\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die Kraft der Steine, angewendet auf die Corstone-Bel\u00e4ge.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/weiku.com.br\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/weiku.com.br\\\/de\\\/\",\"name\":\"Weiku\",\"description\":\"Esquadrias de PVC - Weiku do Brasil\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/weiku.com.br\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/weiku.com.br\\\/de\\\/#\\\/schema\\\/person\\\/a15df1b49db4f0c34776a50f6a0ba70d\",\"name\":\"Mateus Fernandes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/weiku.com.br\\\/wp-content\\\/litespeed\\\/avatar\\\/900ee9f544fa1ea84bffb5ef4c3394f3.jpg?ver=1778464268\",\"url\":\"https:\\\/\\\/weiku.com.br\\\/wp-content\\\/litespeed\\\/avatar\\\/900ee9f544fa1ea84bffb5ef4c3394f3.jpg?ver=1778464268\",\"contentUrl\":\"https:\\\/\\\/weiku.com.br\\\/wp-content\\\/litespeed\\\/avatar\\\/900ee9f544fa1ea84bffb5ef4c3394f3.jpg?ver=1778464268\",\"caption\":\"Mateus Fernandes\"},\"sameAs\":[\"http:\\\/\\\/www.weiku.com.br\"],\"url\":\"https:\\\/\\\/weiku.com.br\\\/de\\\/author\\\/mateus\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die Kraft der Steine, angewendet auf die Corstone-Bel\u00e4ge. - Weiku","description":"Und um den Markt zu revolutionieren, kommt Corstone mit Pers\u00f6nlichkeit und Kreativit\u00e4t. Es ist das erste Belagsprodukt der Weiku-Gruppe...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/weiku.com.br\/de\/die-kraft-der-steine-angewendet-auf-die-corstone-belaege\/","og_locale":"de_DE","og_type":"article","og_title":"Die Kraft der Steine, angewendet auf die Corstone-Bel\u00e4ge. - Weiku","og_description":"Und um den Markt zu revolutionieren, kommt Corstone mit Pers\u00f6nlichkeit und Kreativit\u00e4t. Es ist das erste Belagsprodukt der Weiku-Gruppe...","og_url":"https:\/\/weiku.com.br\/de\/die-kraft-der-steine-angewendet-auf-die-corstone-belaege\/","og_site_name":"Weiku","article_published_time":"2023-10-24T12:00:00+00:00","article_modified_time":"2025-07-22T14:50:36+00:00","og_image":[{"width":1024,"height":431,"url":"https:\/\/weiku.com.br\/wp-content\/uploads\/2023\/10\/banners-site-1024x431.png","type":"image\/png"}],"author":"Mateus Fernandes","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Mateus Fernandes","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/weiku.com.br\/de\/die-kraft-der-steine-angewendet-auf-die-corstone-belaege\/#article","isPartOf":{"@id":"https:\/\/weiku.com.br\/de\/die-kraft-der-steine-angewendet-auf-die-corstone-belaege\/"},"author":{"name":"Mateus Fernandes","@id":"https:\/\/weiku.com.br\/de\/#\/schema\/person\/a15df1b49db4f0c34776a50f6a0ba70d"},"headline":"Die Kraft der Steine, angewendet auf die Corstone-Bel\u00e4ge.","datePublished":"2023-10-24T12:00:00+00:00","dateModified":"2025-07-22T14:50:36+00:00","mainEntityOfPage":{"@id":"https:\/\/weiku.com.br\/de\/die-kraft-der-steine-angewendet-auf-die-corstone-belaege\/"},"wordCount":415,"image":{"@id":"https:\/\/weiku.com.br\/de\/die-kraft-der-steine-angewendet-auf-die-corstone-belaege\/#primaryimage"},"thumbnailUrl":"https:\/\/weiku.com.br\/wp-content\/uploads\/2023\/10\/banners-site.png","articleSection":["Nicht kategorisiert"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/weiku.com.br\/de\/die-kraft-der-steine-angewendet-auf-die-corstone-belaege\/","url":"https:\/\/weiku.com.br\/de\/die-kraft-der-steine-angewendet-auf-die-corstone-belaege\/","name":"Die Kraft der Steine, angewendet auf die Corstone-Bel\u00e4ge. - Weiku","isPartOf":{"@id":"https:\/\/weiku.com.br\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/weiku.com.br\/de\/die-kraft-der-steine-angewendet-auf-die-corstone-belaege\/#primaryimage"},"image":{"@id":"https:\/\/weiku.com.br\/de\/die-kraft-der-steine-angewendet-auf-die-corstone-belaege\/#primaryimage"},"thumbnailUrl":"https:\/\/weiku.com.br\/wp-content\/uploads\/2023\/10\/banners-site.png","datePublished":"2023-10-24T12:00:00+00:00","dateModified":"2025-07-22T14:50:36+00:00","author":{"@id":"https:\/\/weiku.com.br\/de\/#\/schema\/person\/a15df1b49db4f0c34776a50f6a0ba70d"},"description":"Und um den Markt zu revolutionieren, kommt Corstone mit Pers\u00f6nlichkeit und Kreativit\u00e4t. Es ist das erste Belagsprodukt der Weiku-Gruppe...","breadcrumb":{"@id":"https:\/\/weiku.com.br\/de\/die-kraft-der-steine-angewendet-auf-die-corstone-belaege\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/weiku.com.br\/de\/die-kraft-der-steine-angewendet-auf-die-corstone-belaege\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/weiku.com.br\/de\/die-kraft-der-steine-angewendet-auf-die-corstone-belaege\/#primaryimage","url":"https:\/\/weiku.com.br\/wp-content\/uploads\/2023\/10\/banners-site.png","contentUrl":"https:\/\/weiku.com.br\/wp-content\/uploads\/2023\/10\/banners-site.png","width":1600,"height":673},{"@type":"BreadcrumbList","@id":"https:\/\/weiku.com.br\/de\/die-kraft-der-steine-angewendet-auf-die-corstone-belaege\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/weiku.com.br\/de\/"},{"@type":"ListItem","position":2,"name":"Die Kraft der Steine, angewendet auf die Corstone-Bel\u00e4ge."}]},{"@type":"WebSite","@id":"https:\/\/weiku.com.br\/de\/#website","url":"https:\/\/weiku.com.br\/de\/","name":"Weiku","description":"Esquadrias de PVC - Weiku do Brasil","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/weiku.com.br\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/weiku.com.br\/de\/#\/schema\/person\/a15df1b49db4f0c34776a50f6a0ba70d","name":"Mateus Fernandes","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/weiku.com.br\/wp-content\/litespeed\/avatar\/900ee9f544fa1ea84bffb5ef4c3394f3.jpg?ver=1778464268","url":"https:\/\/weiku.com.br\/wp-content\/litespeed\/avatar\/900ee9f544fa1ea84bffb5ef4c3394f3.jpg?ver=1778464268","contentUrl":"https:\/\/weiku.com.br\/wp-content\/litespeed\/avatar\/900ee9f544fa1ea84bffb5ef4c3394f3.jpg?ver=1778464268","caption":"Mateus Fernandes"},"sameAs":["http:\/\/www.weiku.com.br"],"url":"https:\/\/weiku.com.br\/de\/author\/mateus\/"}]}},"_links":{"self":[{"href":"https:\/\/weiku.com.br\/de\/wp-json\/wp\/v2\/posts\/27041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/weiku.com.br\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/weiku.com.br\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/weiku.com.br\/de\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/weiku.com.br\/de\/wp-json\/wp\/v2\/comments?post=27041"}],"version-history":[{"count":1,"href":"https:\/\/weiku.com.br\/de\/wp-json\/wp\/v2\/posts\/27041\/revisions"}],"predecessor-version":[{"id":27042,"href":"https:\/\/weiku.com.br\/de\/wp-json\/wp\/v2\/posts\/27041\/revisions\/27042"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/weiku.com.br\/de\/wp-json\/wp\/v2\/media\/25284"}],"wp:attachment":[{"href":"https:\/\/weiku.com.br\/de\/wp-json\/wp\/v2\/media?parent=27041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/weiku.com.br\/de\/wp-json\/wp\/v2\/categories?post=27041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/weiku.com.br\/de\/wp-json\/wp\/v2\/tags?post=27041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}